{"id":10360,"date":"2023-08-15T16:06:40","date_gmt":"2023-08-15T16:06:40","guid":{"rendered":"https:\/\/blog.netbet.com.mx\/blog\/?p=10360"},"modified":"2023-08-09T16:07:47","modified_gmt":"2023-08-09T16:07:47","slug":"juegos-nuevos-esta-semana-14-08","status":"publish","type":"post","link":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/","title":{"rendered":"Juegos nuevos esta semana 14\/08"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">NetBet es un <\/span><a href=\"https:\/\/casino.netbet.com.mx\/\"><span style=\"font-weight: 400;\">online casino<\/span><\/a><span style=\"font-weight: 400;\"> que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde <\/span><a href=\"https:\/\/casino.netbet.com.mx\/slots\"><span style=\"font-weight: 400;\">tragamonedas<\/span><\/a><span style=\"font-weight: 400;\"> y bingos hasta ruletas y mesas en vivo. Cada uno de los t\u00edtulos de su repertorio te ofrece muchos premios y emociones inigualables. Prueba tu suerte en alguno de los juegos nuevos de esta semana, los cuales te presentamos a continuaci\u00f3n.\u00a0<\/span><\/p>\n<h2><b>Lara Jones is Cleopatra<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Lara Jones is Cleopatra es un juego con tem\u00e1tica egipcia creado por Spearhead Studios. El RTP de esta tragaperras es del 96.46 % y su modelo matem\u00e1tico arroja una alta volatilidad. Para conseguir una ganancia debes obtener tres o m\u00e1s s\u00edmbolos iguales en una l\u00ednea de pago, de izquierda a derecha. Una de las funciones de este slot es el giro de Cleopatra. Esta bonificaci\u00f3n aleatoria reemplazar\u00e1 a cualquier s\u00edmbolo 10, J o Q con el s\u00edmbolo de Cleopatra.<\/span><\/p>\n<p><span style=\"font-weight: 400;\"> Esta caracter\u00edstica de bonificaci\u00f3n s\u00f3lo ocurre durante el juego base. El Wild es otro s\u00edmbolo especial y funciona como un comod\u00edn que sustituye a cualquier otro s\u00edmbolo, excepto al Scatter. Durante las tiradas gratis, todos los Wilds se vuelven pegajosos y permanecen en su posici\u00f3n hasta el final. Para activar esta funci\u00f3n, los Scatters deben aparecer en los rodillos 1, 3 y 5. As\u00ed reclamar\u00e1s hasta 10 tiradas gratis.<\/span><\/p>\n<h2><b>Respin Joker<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Respin Joker es un slot con un dise\u00f1o cl\u00e1sico creado por el reconocido proveedor Synot. Este t\u00edtulo presenta un tablero de 3&#215;3 con 5 l\u00edneas de pago. Para ganar necesitas tiradas con al menos 3 s\u00edmbolos coincidentes. Cuando un carrete completo se llena con el mismo tipo de s\u00edmbolo, \u00a1el valor de la ganancia se duplica! <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los pagos se multiplican por la apuesta total: si salen las cerezas en una l\u00ednea, entonces ganas un premio equivalente al doble de tu apuesta; los mayores premios que puedes conseguir con el resto de los s\u00edmbolos equivalen al 4x de tu apuesta con el lim\u00f3n, 6x con las naranjas, 8x con las ciruelas y 10x con las uvas. Las ganancias m\u00e1s altas provienen del icono de la campana dorada, cuando aparece en cualquier l\u00ednea de pago. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El Wild tiene forma de m\u00e1scara de arlequ\u00edn blanca y no tiene ning\u00fan valor real por s\u00ed mismo. La funci\u00f3n de Respin hace que, cuando el s\u00edmbolo del comod\u00edn hace parte de una combinaci\u00f3n ganadora, este permanezca bloqueado en su lugar. Esto ocurre mientras todas las dem\u00e1s posiciones de los carretes giran una vez m\u00e1s de forma gratuita.\u00a0<\/span><\/p>\n<h2><b>Maverick X<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Maverick X es un juego muy divertido con una encantadora aeronave que fue creado por el equipo creativo de 1&#215;2 gaming. Este t\u00edtulo te ofrece un RTP te\u00f3rico del 95% y una volatilidad debajo del promedio. Maverick X es uno de los \u00fanicos t\u00edtulos disponibles en el mercado con una din\u00e1mica al estilo de Aviator. Para empezar a jugarlo, debes esperar a que empiece el periodo de apuestas y definir el tama\u00f1o de tu importe. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Una vez que hayas definido tu apuesta y el temporizador para la siguiente ronda haya acabado, ver\u00e1s que la aeronave despegar\u00e1 y volar\u00e1 por los cielos, debajo de un multiplicador que muestra tu ganancia potencial. Entre m\u00e1s tiempo est\u00e9 volando la aeronave, m\u00e1s crecer\u00e1 este multiplicador. El objetivo de este t\u00edtulo es dejar que el multiplicador crezca y reclamarlo antes de que el avi\u00f3n desaparezca de la pantalla, ya que, si no lo reclamas antes, habr\u00e1s perdido tu apuesta.<\/span><\/p>\n<p>En NetBet Casino, nos esforzamos por ofrecerte una variada gama de juegos emocionantes. Tambi\u00e9n te garantizamos un entorno seguro para que puedas disfrutar de la emoci\u00f3n del casino en l\u00ednea. Fomentamos el\u00a0<a href=\"https:\/\/casino.netbet.com.mx\/help\/responsible-gambling\">Juego responsable<\/a>\u00a0en cada t\u00edtulo de nuestro cat\u00e1logo. Para m\u00e1s consejos sobre este tema, revisa nuestra p\u00e1gina dedicada a las pol\u00edticas de Juego responsable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo. Cada uno de los t\u00edtulos de su repertorio te ofrece muchos premios y emociones inigualables. Prueba tu suerte en alguno de los juegos nuevos de esta semana, los cuales [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":7370,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1755],"tags":[],"class_list":["post-10360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casino"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Juegos nuevos esta semana 14\/08 | NetBet Mexico<\/title>\n<meta name=\"description\" content=\"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juegos nuevos esta semana 14\/08 | NetBet Mexico\" \/>\n<meta property=\"og:description\" content=\"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Mexico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/netbetcom\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-15T16:06:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@netbet\" \/>\n<meta name=\"twitter:site\" content=\"@netbet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d\"},\"headline\":\"Juegos nuevos esta semana 14\/08\",\"datePublished\":\"2023-08-15T16:06:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\"},\"wordCount\":670,\"publisher\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg\",\"articleSection\":[\"Casino\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\",\"name\":\"Juegos nuevos esta semana 14\/08 | NetBet Mexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg\",\"datePublished\":\"2023-08-15T16:06:40+00:00\",\"description\":\"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg\",\"contentUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Curiosidades de los casinos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.netbet.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juegos nuevos esta semana 14\/08\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/\",\"name\":\"NetBet Mexico\",\"description\":\"Apuestas en linea, consejos y novedades\",\"publisher\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netbet.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\",\"name\":\"NetBet Mexico\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png\",\"contentUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png\",\"width\":258,\"height\":50,\"caption\":\"NetBet Mexico\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/netbetcom\",\"https:\/\/x.com\/netbet\",\"https:\/\/www.instagram.com\/netbetsport\/\",\"https:\/\/ro.pinterest.com\/netbetcom\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juegos nuevos esta semana 14\/08 | NetBet Mexico","description":"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/","og_locale":"es_MX","og_type":"article","og_title":"Juegos nuevos esta semana 14\/08 | NetBet Mexico","og_description":"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.","og_url":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/","og_site_name":"NetBet Mexico","article_publisher":"https:\/\/www.facebook.com\/netbetcom","article_published_time":"2023-08-15T16:06:40+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@netbet","twitter_site":"@netbet","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#article","isPartOf":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d"},"headline":"Juegos nuevos esta semana 14\/08","datePublished":"2023-08-15T16:06:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/"},"wordCount":670,"publisher":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg","articleSection":["Casino"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/","url":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/","name":"Juegos nuevos esta semana 14\/08 | NetBet Mexico","isPartOf":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg","datePublished":"2023-08-15T16:06:40+00:00","description":"NetBet es un online casino que posee un amplio cat\u00e1logo de juegos para ti. Aqu\u00ed encontrar\u00e1s desde tragamonedas y bingos hasta ruletas y mesas en vivo.","breadcrumb":{"@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#primaryimage","url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg","contentUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2020\/05\/Curiosidades-de-los-casinos.jpg","width":1200,"height":800,"caption":"Curiosidades de los casinos"},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.com.mx\/blog\/juegos-nuevos-esta-semana-14-08\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Juegos nuevos esta semana 14\/08"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.com.mx\/blog\/#website","url":"https:\/\/www.netbet.com.mx\/blog\/","name":"NetBet Mexico","description":"Apuestas en linea, consejos y novedades","publisher":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.netbet.com.mx\/blog\/#organization","name":"NetBet Mexico","url":"https:\/\/www.netbet.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png","contentUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png","width":258,"height":50,"caption":"NetBet Mexico"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/netbetcom","https:\/\/x.com\/netbet","https:\/\/www.instagram.com\/netbetsport\/","https:\/\/ro.pinterest.com\/netbetcom\/"]},{"@type":"Person","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"}}]}},"amp_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=10360"}],"version-history":[{"count":1,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10360\/revisions"}],"predecessor-version":[{"id":10361,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10360\/revisions\/10361"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/media\/7370"}],"wp:attachment":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=10360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=10360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=10360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}