{"id":10165,"date":"2023-05-15T10:04:58","date_gmt":"2023-05-15T10:04:58","guid":{"rendered":"https:\/\/blog.netbet.com.mx\/blog\/?p=10165"},"modified":"2023-05-12T10:09:51","modified_gmt":"2023-05-12T10:09:51","slug":"los-juegos-mas-populares-de-esta-semana-15-05","status":"publish","type":"post","link":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/","title":{"rendered":"Los juegos m\u00e1s populares de esta semana 15\/05"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de <\/span><a href=\"https:\/\/casino.netbet.com.mx\/\"><span style=\"font-weight: 400;\">casino online en M\u00e9xico<\/span><\/a><span style=\"font-weight: 400;\"> que ofrece entretenimiento para todos. Ya sea que prefieras juegos de cartas, ruletas o <\/span><a href=\"https:\/\/casino.netbet.com.mx\/slots\"><span style=\"font-weight: 400;\">tragamonedas<\/span><\/a><span style=\"font-weight: 400;\">, explora y encuentra el juego perfecto para ti. Cada uno de los t\u00edtulos presentes en su\u00a0 cat\u00e1logo te ofrece din\u00e1micas divertidas y premios elevados.<\/span><\/p>\n<h2><b>Burning Hot<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">La tragamonedas Burning Hot fue desarrollada por el estudio EGT. Una slot que tiene 5 carretes y 5 l\u00edneas de pago fijas, donde las ganancias m\u00e1ximas alcanzan los 6.000 cr\u00e9ditos. Dispone de dos s\u00edmbolos Scatter, un comod\u00edn y un juego de riesgo para duplicar tus ganancias. Para ganar premios, necesitas una cadena de 2 a 5 im\u00e1genes iguales en cualquiera de las 5 l\u00edneas de pago. Si la cantidad que reclamas es menor a 350 cr\u00e9ditos, entonces existe la posibilidad de jugar una ronda de duplicaci\u00f3n. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El s\u00edmbolo 7 es el que proporciona el mayor pago, te da 6.000 cr\u00e9ditos por 5 s\u00edmbolos iguales. Las uvas y la sand\u00eda otorgan hasta 1.000 cr\u00e9ditos por las combinaciones de 5 s\u00edmbolos. Mientras que la campana, la cereza, el lim\u00f3n, la ciruela y la naranja proporcionan pagos menores. La hoja de tr\u00e9bol es el s\u00edmbolo comod\u00edn, mientras que los Scatter est\u00e1n representados por el d\u00f3lar y la estrella. La tragamonedas Burning Hot tambi\u00e9n cuenta con un bote progresivo que se juega al azar y se divide en 4 niveles. Cada uno de ellos corresponde a un palo de cartas.<\/span><\/p>\n<h2><b>Diamond Plus<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Diamond Plus es una tragamonedas con tem\u00e1tica de frutas creada por EGT Interactive. Presenta una cuadr\u00edcula de carretes con dimensiones de 5&#215;3 y s\u00edmbolos jugosos como melones, uvas y cerezas. Esta slot es divertida y emocionante en cada tirada debido a sus din\u00e1micas y bonificadores. Los diamantes salvajes se expanden para cubrir carretes completos y activar una nueva tirada. En Diamond Plus obtienes combos ganadores con tres, cuatro o cinco s\u00edmbolos iguales. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El siete de la suerte es el signo que paga m\u00e1s, con cinco iguales ganas 100 veces tu apuesta. Adem\u00e1s, la expansi\u00f3n de los diamantes salvajes tambi\u00e9n sustituye a los s\u00edmbolos del juego base para crear m\u00e1s l\u00edneas ganadoras. Otra caracter\u00edstica interesante es la funci\u00f3n de apuesta, que te permite duplicar muchos premios. S\u00f3lo adivina si la pr\u00f3xima carta de juego ser\u00e1 roja o negra para reclamar m\u00e1s dinero. Este juego cuenta con cuatro jackpots progresivos, eso significa que siempre tienes oportunidades para reclamar grandes premios.<\/span><\/p>\n<h2><b>Legendary Beasts<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Legendary Beasts es una emocionante tragamonedas de 3&#215;3 con un carrete adicional y caracter\u00edsticas \u00fanicas. Los puntos se dividen en 2 o 4 con el mismo s\u00edmbolo, eso te permite obtener hasta 1.728 combinaciones ganadoras. La apuesta total por tirada depende del nivel de apuesta, multiplicado por el valor de la moneda. El rango de apuestas comienza\u00a0 con una m\u00ednima de 0.09\u20ac y una m\u00e1xima de 1.800\u20ac. Este juego presenta baja volatilidad y un alto RTP del 97.86%, un porcentaje elevado en comparaci\u00f3n con otras slots. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El carrete multiplicador es otra caracter\u00edstica emocionante, cuando cae genera de forma aleatoria multiplicadores de: 1x, 2x, 3x, 6x o 9x en cada tirada. Estos bonificadores aumentan tus ganancias en cada ronda. Si tienes suerte, entonces alcanzar\u00e1s la ganancia m\u00e1xima de 3.856 veces tu apuesta total. Legendary Beasts es una tragaperras que oculta muchas din\u00e1micas divertidas y muchos premios por tirada.\u00a0<\/span><\/p>\n<p>Cuando eliges a NetBet Casino, tienes a tu disposici\u00f3n una inmensa diversidad de slots de la mejor calidad. Juegues lo que juegues, recuerda siempre apostar responsablemente. Aqu\u00ed en NetBet, el bienestar de nuestros jugadores es nuestra prioridad principal \u2013 para m\u00e1s informaci\u00f3n, checa nuestra p\u00e1gina de consejos y herramientas de\u00a0<a href=\"https:\/\/casino.netbet.com.mx\/help\/responsible-gambling\">juego responsable<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de cartas, ruletas o tragamonedas, explora y encuentra el juego perfecto para ti. Cada uno de los t\u00edtulos presentes en su\u00a0 cat\u00e1logo te ofrece din\u00e1micas divertidas y premios elevados. Burning Hot La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":8418,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1755],"tags":[],"class_list":["post-10165","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-casino"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico<\/title>\n<meta name=\"description\" content=\"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\" \/>\n<meta property=\"og:locale\" content=\"es_MX\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico\" \/>\n<meta property=\"og:description\" content=\"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\" \/>\n<meta property=\"og:site_name\" content=\"NetBet Mexico\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/netbetcom\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-15T10:04:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@netbet\" \/>\n<meta name=\"twitter:site\" content=\"@netbet\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d\"},\"headline\":\"Los juegos m\u00e1s populares de esta semana 15\/05\",\"datePublished\":\"2023-05-15T10:04:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\"},\"wordCount\":645,\"publisher\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg\",\"articleSection\":[\"Casino\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\",\"name\":\"Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico\",\"isPartOf\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg\",\"datePublished\":\"2023-05-15T10:04:58+00:00\",\"description\":\"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg\",\"contentUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg\",\"width\":1200,\"height\":800,\"caption\":\"casino 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.netbet.com.mx\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los juegos m\u00e1s populares de esta semana 15\/05\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#website\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/\",\"name\":\"NetBet Mexico\",\"description\":\"Apuestas en linea, consejos y novedades\",\"publisher\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.netbet.com.mx\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#organization\",\"name\":\"NetBet Mexico\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png\",\"contentUrl\":\"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png\",\"width\":258,\"height\":50,\"caption\":\"NetBet Mexico\"},\"image\":{\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/netbetcom\",\"https:\/\/x.com\/netbet\",\"https:\/\/www.instagram.com\/netbetsport\/\",\"https:\/\/ro.pinterest.com\/netbetcom\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico","description":"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/","og_locale":"es_MX","og_type":"article","og_title":"Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico","og_description":"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de","og_url":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/","og_site_name":"NetBet Mexico","article_publisher":"https:\/\/www.facebook.com\/netbetcom","article_published_time":"2023-05-15T10:04:58+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@netbet","twitter_site":"@netbet","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#article","isPartOf":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/"},"author":{"name":"admin","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d"},"headline":"Los juegos m\u00e1s populares de esta semana 15\/05","datePublished":"2023-05-15T10:04:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/"},"wordCount":645,"publisher":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#organization"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg","articleSection":["Casino"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/","url":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/","name":"Los juegos m\u00e1s populares de esta semana 15\/05 | NetBet Mexico","isPartOf":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage"},"thumbnailUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg","datePublished":"2023-05-15T10:04:58+00:00","description":"En NetBet, encontrar\u00e1s una extensa selecci\u00f3n de juegos de casino online en M\u00e9xico que ofrece entretenimiento para todos. Ya sea que prefieras juegos de","breadcrumb":{"@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#primaryimage","url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg","contentUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2021\/03\/casino-online-in-Greece.jpg","width":1200,"height":800,"caption":"casino 1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.netbet.com.mx\/blog\/los-juegos-mas-populares-de-esta-semana-15-05\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.netbet.com.mx\/blog\/"},{"@type":"ListItem","position":2,"name":"Los juegos m\u00e1s populares de esta semana 15\/05"}]},{"@type":"WebSite","@id":"https:\/\/www.netbet.com.mx\/blog\/#website","url":"https:\/\/www.netbet.com.mx\/blog\/","name":"NetBet Mexico","description":"Apuestas en linea, consejos y novedades","publisher":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.netbet.com.mx\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.netbet.com.mx\/blog\/#organization","name":"NetBet Mexico","url":"https:\/\/www.netbet.com.mx\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png","contentUrl":"https:\/\/www.netbet.com.mx\/blog\/wp-content\/uploads\/2016\/09\/cropped-logo.png","width":258,"height":50,"caption":"NetBet Mexico"},"image":{"@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/netbetcom","https:\/\/x.com\/netbet","https:\/\/www.instagram.com\/netbetsport\/","https:\/\/ro.pinterest.com\/netbetcom\/"]},{"@type":"Person","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/c2b3fddc4834e046e6540e9c0616379d","name":"admin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.netbet.com.mx\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b5a865bc5f24d98d2e64f5ed06e586d71ad071c314dd61391d409e80b723a28?s=96&d=mm&r=g","caption":"admin"}}]}},"amp_enabled":true,"post_mailing_queue_ids":[],"_links":{"self":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10165","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/comments?post=10165"}],"version-history":[{"count":1,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10165\/revisions"}],"predecessor-version":[{"id":10166,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/posts\/10165\/revisions\/10166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/media\/8418"}],"wp:attachment":[{"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/media?parent=10165"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/categories?post=10165"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.netbet.com.mx\/blog\/wp-json\/wp\/v2\/tags?post=10165"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}